{"id":14562,"date":"2022-12-13T10:57:42","date_gmt":"2022-12-13T10:57:42","guid":{"rendered":"https:\/\/bluetab.net\/?p=14562"},"modified":"2022-12-13T10:57:42","modified_gmt":"2022-12-13T10:57:42","slug":"una-estrategia-analitica-eficiente","status":"publish","type":"post","link":"https:\/\/bluetab.com\/en\/2022\/12\/una-estrategia-analitica-eficiente\/","title":{"rendered":"Una estrategia anal\u00edtica eficiente"},"content":{"rendered":"<h1>Una estrategia anal\u00edtica eficiente<\/h1>\n<figure><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/03\/Isotipo-Bluetab-150x150.png\" alt=\"\" loading=\"lazy\" \/><\/figure>\n<h4>Bluetab<\/h4>\n<h2><b>Where<\/b> <b>we<\/b><b> are<\/b><\/h2>\n<p>De acuerdo con el informe Data never Sleeps, elaborado por Domo, cada d\u00eda se crean en Internet m\u00e1s de\u00a0<b>2,5 billones de bytes de datos, <\/b>y se estima que cada\u00a0<b>persona<\/b>\u00a0en la Tierra\u00a0<b>genera<\/b>\u00a01,7MB de\u00a0<b>datos<\/b>\u00a0por segundo. Somos 7.75 billones.<\/p>\n<p>Vivimos en un momento de generaci\u00f3n extraordinaria de datos, y en el que las inversiones en los \u00faltimos a\u00f1os y la previstas en los pr\u00f3ximo, crecen de forma exponencial. Pero analistas hoy como McKinsey o el MIT Review, coinciden al establecer que s\u00f3lo el 56% del mercado declara usar exitosamente la AI, que el 95% aun no son capaces de gestionar datos no estructurados y a\u00fan hoy 2 de cada 3 proyectos de datos incumplen plazos de entrada en producci\u00f3n.<\/p>\n<p>Como especialistas en este mercado, entendemos que esto trata fundamentalmente, por un lado de que los ecosistemas y las tecnolog\u00edas en torno al dato est\u00e1n en continua evoluci\u00f3n y en cualquier caso lejos de una madurez consolidada. Y por otro lado de que cada empresa est\u00e1 en un punto de ese \u201cjournie\u201d o maduraci\u00f3n requerida para optimizar el uso de este \u201cnuevo oro negro\u201d. Y esta maduraci\u00f3n de las empresas tiene al menos tres componentes relevantes, la alineaci\u00f3n de la estrategia de negocio y la tecnolog\u00eda, la capacidad tecnol\u00f3gica adecuada, y por \u00faltimo la alineaci\u00f3n organizativa y cultural que asegure la armon\u00eda entre negocio y tecnolog\u00eda.<\/p>\n<p>Seg\u00fan nuestra experiencia, al menos 1 de cada 4 empresas no han iniciado o est\u00e1n al inicio de ese camino hace una empresa \u201cdata driven\u201d. Al menos 1 de cada 3 empresas no tienen una arquitectura tecnol\u00f3gica adecuada y capaz de dar cobertura a sus necesidades. Y s\u00f3lo 1 de cada 4 empresas tienen una estrategia clara de explotaci\u00f3n del valor de sus datos. Hoy hay ejemplos de corporaciones en M\u00e9xico que desde un mundo transaccional cl\u00e1sico casi est\u00e1n iniciando ese \u201cjourney\u201d y, evidentemente en el otro extremo tenemos \u201cunicornios\u201d digitales donde el valor del dato se extrae hasta la \u00faltima gota.<\/p>\n<figure>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.domo.com\/learn\/infographic\/data-never-sleeps-9\" target=\"_blank\" rel=\"noopener\"><br \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"564\" height=\"966\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia.png\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia.png 564w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia-175x300.png 175w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\t\t\t\t\t\t\t\t<\/a><figcaption>https:\/\/www.domo.com\/learn\/infographic\/data-never-sleeps-9<\/figcaption><\/figure>\n<h2><b>Las bases para una estrategia anal\u00edtica competitiva<\/b><\/h2>\n<p>Parece una obviedad pero medir la eficacia de tus procesos y tu actividad de negocio es la base de inicio para identificar las fuentes de mayor impacto en tu estrategia anal\u00edtica. La estad\u00edstica, los modelos predictivos y los algoritmos complejos ya estaban con nosotros hace m\u00e1s de 50 a\u00f1os. Pero como bien es sabido la eficacia de la muestra aumenta conforme aumenta el volumen de la muestra a analizar, y hoy el big data permite evaluar muestras de volumen casi infinito.<\/p>\n<p>Con la capacidad de proceso actual disponible, la eficacia de la estad\u00edstica compleja es varias dimensiones superior a procesos de hace s\u00f3lo 10 a\u00f1os, pero adem\u00e1s ahora, los algoritmos complejos est\u00e1n disponibles en los \u201cmarket places\u201d de los principales clouds (AWS, GCP y Azure) para que te los bajes, los parametrices y los despliegues casi en unos pocos \u201cclicks\u201d.\u00a0\u00a0<\/p>\n<p>Partiendo de ello, ahora debemos asegurar que estrategia de negocio y tecnolog\u00eda est\u00e1n alineados, forman un mismo equipo; cualquier decisi\u00f3n estrat\u00e9gica que no est\u00e1 soportada por la tecnolog\u00eda adecuada no escalar\u00e1 adecuadamente. En la primera d\u00e9cada de los 2000\u2019s todos los grandes CEOs eran financieros, hoy son tecn\u00f3logos. Todo el equipo directivo debe entender de tecnolog\u00eda, y esa cultura adem\u00e1s de la del\u00a0 negocio, debe permear en toda la organizaci\u00f3n con diferentes niveles de conocimiento.<\/p>\n<p>El perfil hoy de los profesionales debe adecuarse hoy a la volatilidad y los cambios continuos, tanto por los cambios de contexto econ\u00f3mico como por la continua evoluci\u00f3n de las tecnolog\u00edas. Todos nosotros, profesionales o ejecutivos, debemos estar en constante evoluci\u00f3n, en formaci\u00f3n continua y apoy\u00e1ndonos en los diferentes equipos en nuestra organizaci\u00f3n. El modelo de silos departamentales ha dado paso a ecosistemas de dominios de negocio en los que conviven diferentes \u00e1reas de conocimiento y esto asegura mayor compromiso y mejores resultados.\u00a0<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"752\" height=\"856\" src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia2.png\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia2.png 752w, https:\/\/bluetab.net\/wp-content\/uploads\/2022\/12\/estrategia2-264x300.png 264w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<h2><b>C\u00f3mo establecer una estrategia anal\u00edtica eficaz y la generaci\u00f3n de nuevos ecosistemas <\/b><\/h2>\n<p>Muchas empresas nos preguntan, bien y, \u00bfahora por donde empiezo?. La pregunta tiene una sencilla respuesta, por lo que tienes actualmente, midiendo y estableciendo suficientes KPIs que te permitan evaluar c\u00f3mo est\u00e1s ejecutando tus procesos. De esta sencilla manera y con esos datos que ya tienes de tus clientes y procesos, puedes empezar primero a describir como es tu ecosistema (anal\u00edtica descriptiva), y posteriormente a identificar los puntos de actuaci\u00f3n, mejora y cuellos de botella donde actuar. Y entonces establecer de forma precisa y cre\u00edble la posible predicci\u00f3n de ahorros ROI (anal\u00edtica predictiva). Esta primera fase de incremento de eficiencia de tus procesos actuales es, siendo la m\u00e1s sencilla, la que probablemente te aporte los mayores retornos y la capacidad para abordar pasos posteriores.<\/p>\n<p>Una vez atacados los procesos core, debemos focalizarnos en el crecimiento de las ventas de nuestro negocio core mediante el conocimiento que tenemos de nuestro cliente, de su perfil y modelos de consumo. Aplicando ciencia de datos (anal\u00edtica prescriptiva) podremos establecer patrones no evidentes que nos permitir\u00e1n mediante micro campa\u00f1as y acciones personalizadas elevar sustancialmente nuestros ratios de ventas tanto \u201ccross\u201d como \u201cup selling\u201d.<\/p>\n<p>Finalmente en este proceso de evoluci\u00f3n de nuestros anal\u00edtica y con el conocimiento 360\u00ba de nuestros clientes, debemos dar un salto de mayor riesgo y a la vez de mayor impacto, la generaci\u00f3n de nuevos ecosistemas de valor para nuestros clientes. El cruce con informaci\u00f3n externa, y el entendimiento de patrones y necesidades de nuestros clientes no limitados a nuestros modelos actuales de monetizaci\u00f3n, nos permitir\u00e1 identificar necesidades que podemos satisfacer a nuestros clientes, s\u00f3lo haciendo peque\u00f1as ampliaciones en nuestra cadena de valor. Un ejemplo sencillo es que una cadena de farmacia puede vender m\u00e1s eficazmente seguros m\u00e9dicos que otros canales alternativos porque conoce la medicaci\u00f3n de sus clientes.<\/p>\n<h2>MEDIR<br \/>&#038;nbsp<\/h2>\n<ul>\n<li>\n\t\t\t\t\t\t\t\t\t\tDatos de medici\u00f3n\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tEstad\u00edstica avanzada\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tInteligencia artificial\n\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul>\n<h2>ADECUAR MIS RECURSOS<br \/>\n<\/h2>\n<ul>\n<li>\n\t\t\t\t\t\t\t\t\t\tTecnolog\u00eda alineada a la estrategia\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tUna infraestructura tecnol\u00f3gica adecuada\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tUna organizaci\u00f3n con la cultura y el talento\n\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul>\n<h2>GENERAR VALOR CRECIENTE<br \/>\n<\/h2>\n<ul>\n<li>\n\t\t\t\t\t\t\t\t\t\tEficientar los procesos existentes\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tGenerar aumento en las ventas core\n\t\t\t\t\t\t\t\t\t<\/li>\n<li>\n\t\t\t\t\t\t\t\t\t\tGeneraci\u00f3n de nuevos ecosistemas\n\t\t\t\t\t\t\t\t\t<\/li>\n<\/ul>\n<h5>\u00bfQuieres saber m\u00e1s de lo que ofrecemos y ver otros casos de \u00e9xito?<\/h5>\n<p>\t\t\t<a href=\"\/\" role=\"button\"><br \/>\n\t\t\t\t\t\tDESCUBRE BLUETAB<br \/>\n\t\t\t\t\t<\/a><\/p>\n<p><b>SOLUCIONES, <\/b>SOMOS EXPERTOS<\/p>\n<p>\t\t\t\t\t<a href=\"\/soluciones\/data-strategy\/\"><\/p>\n<h5>DATA STRATEGY<\/h5>\n<p>\t\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t<a href=\"\/soluciones\/data-fabric\/\"><\/p>\n<h5>DATA FABRIC<\/h5>\n<p>\t\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t<a href=\"\/soluciones\/augmented-analytics\/\"><\/p>\n<h5>AUGMENTED ANALYTICS<\/h5>\n<p>\t\t\t\t\t\t<\/a><\/p>\n<p>Te puede interesar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una estrategia anal\u00edtica eficiente Bluetab Where we are De acuerdo con el informe Data never Sleeps, elaborado por Domo, cada d\u00eda se crean en Internet m\u00e1s de\u00a02,5 billones de bytes de datos, y se estima que cada\u00a0persona\u00a0en la Tierra\u00a0genera\u00a01,7MB de\u00a0datos\u00a0por segundo. Somos 7.75 billones. Vivimos en un momento de generaci\u00f3n extraordinaria de datos, y en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,18],"tags":[],"class_list":["post-14562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-tendencias"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/posts\/14562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/comments?post=14562"}],"version-history":[{"count":0,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/posts\/14562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/media\/20822"}],"wp:attachment":[{"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/media?parent=14562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/categories?post=14562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluetab.com\/en\/wp-json\/wp\/v2\/tags?post=14562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}