{"id":14248,"date":"2022-09-12T11:35:05","date_gmt":"2022-09-12T11:35:05","guid":{"rendered":"https:\/\/beta.bluetab.net\/?p=14248"},"modified":"2022-10-03T18:50:12","modified_gmt":"2022-10-03T18:50:12","slug":"caracteristicas-esenciales-que-debemos-tener-en-cuenta-al-adoptar-un-paradigma-en-la-nube","status":"publish","type":"post","link":"https:\/\/bluetab.com\/es\/caracteristicas-esenciales-que-debemos-tener-en-cuenta-al-adoptar-un-paradigma-en-la-nube\/","title":{"rendered":"Caracter\u00edsticas esenciales que debemos tener en cuenta al adoptar un paradigma en la nube"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14248\" class=\"elementor elementor-14248\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae9e51a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae9e51a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22b2db4\" data-id=\"22b2db4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27a9cf5\" data-id=\"27a9cf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2584c6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2584c6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e62396e\" data-id=\"e62396e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a61d0 elementor-widget elementor-widget-heading\" data-id=\"41a61d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Caracter\u00edsticas esenciales que debemos tener en cuenta al adoptar un paradigma en la nube<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b9eec41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9eec41\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-83094b6\" data-id=\"83094b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6aa93ea elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"6aa93ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.linkedin.com\/in\/alejandro-le%C3%B3n-valencia-25832a117\/\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/06\/alejandro-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-14021 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro-150x150.jpg 150w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro-75x75.jpg 75w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro.jpg 159w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.linkedin.com\/in\/alejandro-le%C3%B3n-valencia-25832a117\/\" target=\"_blank\">Alejandro Le\u00f3n<\/a><\/h4><p class=\"elementor-image-box-description\">Delivery Manager<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4b8be14\" data-id=\"4b8be14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ffde65 elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-circle elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"0ffde65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-48f667b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48f667b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-73dfdc5\" data-id=\"73dfdc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-274ea03 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"274ea03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"534\" src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-1024x534.jpg\" class=\"attachment-large size-large wp-image-14256\" alt=\"\" srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-1024x534.jpg 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-300x156.jpg 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-768x400.jpg 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia.jpg 1136w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eeaa01 elementor-widget elementor-widget-text-editor\" data-id=\"6eeaa01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <a href=\"https:\/\/www.nist.gov\/\">NIST<\/a> (<em>National Institute of Standards and Technology<\/em>), habla de las <strong>5 caracter\u00edsticas esenciales para una<\/strong> <strong>buena administraci\u00f3n e implementaci\u00f3n del paradigma en la nube<\/strong>. En este art\u00edculo se revisar\u00e1n estas caracter\u00edsticas en profundidad, ya que son aspectos importantes para tener en cuenta al momento adoptar el c\u00f3mputo en la nube.<br \/><br \/><\/p><h4><strong>Caracter\u00edsticas esenciales<\/strong><\/h4><p>Existe una variedad de servicios diferentes que se ofrecen bajo la modalidad de c\u00f3mputo en la nube, y cada uno de los servicios ofrecidos tiene un fin \u00fanico. Sin embargo, existe una serie de caracter\u00edsticas comunes que define al c\u00f3mputo en la nube, y que hace posible identificarlo como tal.<\/p><p>Seg\u00fan el NIST, las 5 caracter\u00edsticas esenciales del c\u00f3mputo en la nube son:<\/p><ul><li>Autoservicio bajo demanda<\/li><li>Despliegue de infraestructura desde la red<\/li><li>Agrupaci\u00f3n de recursos<\/li><li>Elasticidad<\/li><li>Medir un servicio<br \/><br \/><\/li><\/ul><p>Para entenderlas mejor, echemos un vistazo al detalle de cada uno de estos puntos.<br \/><br \/><\/p><h4><strong>Autoservicio bajo demanda<\/strong><\/h4><p>En estos casos, cada uno de los usuarios u organizaciones que opta por utilizar alguna de las ofertas de servicios de c\u00f3mputo en la nube es responsable de la <strong>configuraci\u00f3n de los recursos y el despliegue de estos<\/strong>.<\/p><p>De esta forma, el usuario final es quien decide que recursos quiere o necesita utilizar y cu\u00e1l ser\u00e1 la capacidad asignada a cada uno de los recursos, y es el mismo usuario quien puede configurar estas opciones desde un centro de administraci\u00f3n de dichos recursos.<br \/><br \/><\/p><h4><strong>Despliegue de infraestructura desde la red<\/strong><\/h4><p>Todos los servicios ofrecidos bajo el paradigma de c\u00f3mputo en la nube deben de ser accesibles a trav\u00e9s de internet, de forma que un usuario puede <strong>hacer uso de ellos en cualquier momento<\/strong> de acuerdo con sus necesidades, y, muy importante desde cualquier parte del mundo, sin necesidad de tener acceso f\u00edsico a la infraestructura que brinda soporte.<br \/><br \/><\/p><h4><strong>Agrupaci\u00f3n de recursos (Disposici\u00f3n de infraestructura)<\/strong><\/h4><p>Cada proveedor de servicios de c\u00f3mputo en la nube mantiene un gran n\u00famero de recursos de <em>hardware<\/em> disponibles para sus clientes. Cada que uno de ellos realiza una solicitud y el proveedor asigna los recursos mediante un modelo de m\u00faltiples tenencias. Esto, en esencia significa que <strong>todos sus clientes est\u00e1n haciendo uso de la una infraestructura compartida<\/strong>. Adem\u00e1s, todos los recursos disponibles se agrupan por cliente, al cual se le asigna un acceso \u00fanico para cada uno de ellos. De esta forma, cada cliente solo puede ver sus recursos y no tiene conocimiento de los recursos asignados a otros clientes.<br \/><br \/><\/p><h4><strong>Elasticidad<\/strong><\/h4><p>Sin importar cual sea el proveedor de c\u00f3mputo en la nube, el usuario cuenta con una flexibilidad en el despliegue de los recursos. Esta flexibilidad es una <strong>abstracci\u00f3n del despliegue de la infraestructura f\u00edsica<\/strong> que el proveedor de servicios debe realizar para satisfacer las necesidades del cliente.<\/p><p>La infraestructura que soporta los centros de datos de los proveedores de los servicios generalmente hace uso de t\u00e9cnicas de c\u00f3mputo distribuido o virtualizaci\u00f3n, que son transparentes para el usuario final.<\/p><p>De esta forma, <strong>el usuario tiene el control sobre los recursos que necesita<\/strong>, por lo que puede realizar peticiones para aumentar o disminuir las cantidades y\/o capacidades de los recursos contratados, y el proveedor debe ser el encargado de administrar ese cambio en su infraestructura de forma transparente y sencilla para dar una respuesta r\u00e1pida y satisfactoria a las solicitudes de sus usuarios.<br \/><br \/><\/p><h4><strong>Maneras de medir el servicio<\/strong><\/h4><p>Los proveedores de servicios de c\u00f3mputo en la nube establecen controles para poder realizar una <strong>medici\u00f3n de los servicios utilizados por los usuarios<\/strong>. Dependiendo del tipo de recurso ofrecido, se acuerda y establece con el usuario un m\u00e9todo de medici\u00f3n de uso de este, por lo general es por uso, o por servicio.<\/p><p>Por ejemplo, en un servicio de almacenamiento de datos en la nube el proveedor puede establecer un precio fijo para los archivos almacenados, o por el tiempo de almacenamiento, o por el espacio de almacenamiento utilizando, o una combinaci\u00f3n de 3 factores.<\/p><p><strong>\u00a0<\/strong><\/p><h4><strong>Conclusiones<\/strong><\/h4><p>El c\u00f3mputo en la nube representa una <strong>evoluci\u00f3n con respecto a un modelo de c\u00f3mputo tradicional<\/strong>, en el cual particulares u organizaciones necesitan adquirir todos los elementos necesarios para construir una infraestructura tecnol\u00f3gica capaz de soportar sus operaciones o nuevos proyectos.<\/p><p><strong>La oferta de servicios de c\u00f3mputo en la nube hace m\u00e1s sencillo la implementaci\u00f3n de sistemas de informaci\u00f3n<\/strong>, sin la necesidad de contar con espacio f\u00edsico para la instalaci\u00f3n de equipos f\u00edsicos, y con un potencial ahorro al hacer uso de modelos de cobro como son las suscripciones de pago por uso.<\/p><p>Es importante subrayar que el c\u00f3mputo en la nube no es un reemplazo directo para la implementaci\u00f3n de un centro de datos en una organizaci\u00f3n, sino que representa una alternativa con un <strong>diferente modo de operaci\u00f3n<\/strong> y un <strong>potencial ahorro en costos<\/strong>. Queda como responsabilidad de las organizaciones realizar un estudio para verificar la factibilidad en la contrataci\u00f3n de servicios de c\u00f3mputo en la nube y el modelo de servicios requerido seg\u00fan sus necesidades.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1be251e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1be251e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-edfbd67\" data-id=\"edfbd67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ebcb6e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ebcb6e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d02533\" data-id=\"3d02533\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c59fc49 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"c59fc49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.linkedin.com\/in\/alejandro-le%C3%B3n-valencia-25832a117\/\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"150\" height=\"150\" data-src=\"https:\/\/bluetab.net\/wp-content\/uploads\/2022\/06\/alejandro-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-14021 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro-150x150.jpg 150w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro-75x75.jpg 75w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/alejandro.jpg 159w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h4 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.linkedin.com\/in\/alejandro-le%C3%B3n-valencia-25832a117\/\" target=\"_blank\">Alejandro Le\u00f3n<\/a><\/h4><p class=\"elementor-image-box-description\">Delivery Manager<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-133365a\" data-id=\"133365a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c55b3a elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-circle elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"3c55b3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c775aa0 elementor-widget elementor-widget-spacer\" data-id=\"c775aa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e334282 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e334282\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-186a982\" data-id=\"186a982\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b442409 elementor-widget elementor-widget-heading\" data-id=\"b442409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres saber m\u00e1s de lo que ofrecemos y ver otros casos de \u00e9xito?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adfb080 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"adfb080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/es\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DESCUBRE BLUETAB<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc31455 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"dc31455\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-685ab40\" data-id=\"685ab40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5c9322 elementor-widget elementor-widget-text-editor\" data-id=\"a5c9322\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>SOLUCIONES, <\/b>SOMOS EXPERTOS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f0b5e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f0b5e8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2c61cc0\" data-id=\"2c61cc0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e934fc9 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"e934fc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"\/es\/soluciones\/data-strategy\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg lazyload\" style=\"background-image:inherit;\" role=\"img\" aria-label=\"strategy-opt\" data-bg-image=\"url(https:\/\/bluetab.net\/wp-content\/uploads\/2020\/10\/strategy-opt.jpg)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tDATA STRATEGY\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0ecb859\" data-id=\"0ecb859\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29d6ad9 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"29d6ad9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"\/es\/soluciones\/data-fabric\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg lazyload\" style=\"background-image:inherit;\" role=\"img\" aria-label=\"fabric-opt\" data-bg-image=\"url(https:\/\/bluetab.net\/wp-content\/uploads\/2020\/10\/fabric-opt.jpg)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tDATA FABRIC\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b7293d2\" data-id=\"b7293d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e2ca20 elementor-cta--skin-cover elementor-cta--valign-middle elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"9e2ca20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"\/es\/soluciones\/augmented-analytics\/\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg lazyload\" style=\"background-image:inherit;\" role=\"img\" aria-label=\"AUGMENTED-ANALYTICS-opt\" data-bg-image=\"url(https:\/\/bluetab.net\/wp-content\/uploads\/2020\/10\/AUGMENTED-ANALYTICS-opt.jpg)\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tAUGMENTED ANALYTICS\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fb7705a\" data-id=\"fb7705a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89468bd elementor-widget elementor-widget-text-editor\" data-id=\"89468bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Te puede interesar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c139676 elementor-posts--align-left elementor-grid-1 elementor-posts--thumbnail-left elementor-hidden-phone elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"c139676\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20303 post type-post status-publish format-standard has-post-thumbnail category-blog-es category-tech entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/domina-los-costos-en-la-nube-optimizacion-de-gcs-y-bigquery-en-google-cloud\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"150\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2025\/03\/Parte-de-arriba-linkidin-3-300x150.png\" class=\"attachment-medium size-medium wp-image-20340 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2025\/03\/Parte-de-arriba-linkidin-3-300x150.png 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2025\/03\/Parte-de-arriba-linkidin-3-1024x512.png 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2025\/03\/Parte-de-arriba-linkidin-3-768x384.png 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2025\/03\/Parte-de-arriba-linkidin-3.png 1200w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/150;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/domina-los-costos-en-la-nube-optimizacion-de-gcs-y-bigquery-en-google-cloud\/\" >\n\t\t\t\tDomina los Costos en la Nube: Optimizaci\u00f3n de GCS y BigQuery en Google Cloud\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmarzo 17, 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/domina-los-costos-en-la-nube-optimizacion-de-gcs-y-bigquery-en-google-cloud\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Domina los Costos en la Nube: Optimizaci\u00f3n de GCS y BigQuery en Google Cloud\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-11105 post type-post status-publish format-standard has-post-thumbnail category-blog-es category-noticias entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/bluetab-se-incorporara-a-ibm\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"162\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2021\/07\/dest-ibm-es-300x162.png\" class=\"attachment-medium size-medium wp-image-11214 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2021\/07\/dest-ibm-es-300x162.png 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2021\/07\/dest-ibm-es-1024x553.png 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2021\/07\/dest-ibm-es-768x415.png 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2021\/07\/dest-ibm-es.png 1500w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/162;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/bluetab-se-incorporara-a-ibm\/\" >\n\t\t\t\tBluetab se incorporar\u00e1 a IBM\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tjulio 9, 2021\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/bluetab-se-incorporara-a-ibm\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Bluetab se incorporar\u00e1 a IBM\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13376 post type-post status-publish format-standard has-post-thumbnail category-blog-es category-interes category-practices category-tech entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/databricks-sobre-azure-una-perspectiva-de-arquitectura-parte-2\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"150\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/03\/4-300x150.png\" class=\"attachment-medium size-medium wp-image-17835 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/03\/4-300x150.png 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/03\/4-1024x512.png 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/03\/4-768x384.png 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/03\/4.png 1200w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/150;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/databricks-sobre-azure-una-perspectiva-de-arquitectura-parte-2\/\" >\n\t\t\t\tDatabricks sobre Azure &#8211; Una perspectiva de Arquitectura (parte 2)\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmarzo 24, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/databricks-sobre-azure-una-perspectiva-de-arquitectura-parte-2\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Databricks sobre Azure &#8211; Una perspectiva de Arquitectura (parte 2)\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31f886f elementor-posts--align-left elementor-grid-1 elementor-hidden-desktop elementor-hidden-tablet elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"31f886f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14133 post type-post status-publish format-standard has-post-thumbnail category-blog-es category-tech entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/data-mesh\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"156\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/07\/DM-300x156.jpg\" class=\"attachment-medium size-medium wp-image-14201 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/07\/DM-300x156.jpg 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/07\/DM-1024x534.jpg 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/07\/DM-768x400.jpg 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/07\/DM.jpg 1136w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/156;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/data-mesh\/\" >\n\t\t\t\tData Mesh\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tjulio 27, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/data-mesh\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Data Mesh\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13731 post type-post status-publish format-standard has-post-thumbnail category-blog-es category-tech entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/gobierno-del-dato-una-mirada-en-la-realidad-y-el-futuro\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"210\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/05\/gd-300x210.jpg\" class=\"attachment-medium size-medium wp-image-13733 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/05\/gd-300x210.jpg 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/05\/gd-1024x718.jpg 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/05\/gd-768x539.jpg 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/05\/gd.jpg 1404w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/210;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/gobierno-del-dato-una-mirada-en-la-realidad-y-el-futuro\/\" >\n\t\t\t\tGobierno del Dato: Una mirada en la realidad y el futuro\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmayo 18, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/gobierno-del-dato-una-mirada-en-la-realidad-y-el-futuro\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre Gobierno del Dato: Una mirada en la realidad y el futuro\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14012 post type-post status-publish format-standard has-post-thumbnail category-blog category-blog-es category-outstanding category-tech entry\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/bluetab.com\/es\/modelos-de-entrega-de-servicios-en-la-nube\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" data-src=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-300x200.jpg\" class=\"attachment-medium size-medium wp-image-14036 lazyload\" alt=\"\" data-srcset=\"https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-300x200.jpg 300w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-1024x683.jpg 1024w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-768x512.jpg 768w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-1536x1024.jpg 1536w, https:\/\/bluetab.com\/wp-content\/uploads\/2022\/06\/cloud-service-data-security-concept-2021-08-26-16-18-12-utc-2048x1365.jpg 2048w\" data-sizes=\"(max-width: 300px) 100vw, 300px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/200;\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/bluetab.com\/es\/modelos-de-entrega-de-servicios-en-la-nube\/\" >\n\t\t\t\tMODELOS DE ENTREGA DE SERVICIOS EN LA NUBE\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tjunio 27, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/bluetab.com\/es\/modelos-de-entrega-de-servicios-en-la-nube\/\" aria-label=\"M\u00e1s informaci\u00f3n sobre MODELOS DE ENTREGA DE SERVICIOS EN LA NUBE\" tabindex=\"-1\" >\n\t\t\tLEER M\u00c1S\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Caracter\u00edsticas esenciales que debemos tener en cuenta al adoptar un paradigma en la nube Alejandro Le\u00f3n Delivery Manager El NIST (National Institute of Standards and<\/p>\n","protected":false},"author":1,"featured_media":14256,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[21,19,634,631],"tags":[],"class_list":{"0":"post-14248","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-blog-es","8":"category-blog","9":"category-outstanding","10":"category-tech","11":"entry"},"uagb_featured_image_src":{"full":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia.jpg",1136,592,false],"thumbnail":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-150x150.jpg",150,150,true],"medium":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-300x156.jpg",300,156,true],"medium_large":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-768x400.jpg",768,400,true],"large":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-1024x534.jpg",1024,534,true],"1536x1536":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia.jpg",1136,592,false],"2048x2048":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia.jpg",1136,592,false],"sidebar-featured":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-75x75.jpg",75,75,true],"genesis-singular-images":["https:\/\/bluetab.com\/wp-content\/uploads\/2022\/09\/cloud-estrategia-702x526.jpg",702,526,true]},"uagb_author_info":{"display_name":"Bluetab","author_link":"https:\/\/bluetab.com\/es\/author\/user\/"},"uagb_comment_info":0,"uagb_excerpt":"Caracter\u00edsticas esenciales que debemos tener en cuenta al adoptar un paradigma en la nube Alejandro Le\u00f3n Delivery Manager El NIST (National Institute of Standards and","_links":{"self":[{"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/posts\/14248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/comments?post=14248"}],"version-history":[{"count":13,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/posts\/14248\/revisions"}],"predecessor-version":[{"id":14355,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/posts\/14248\/revisions\/14355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/media\/14256"}],"wp:attachment":[{"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/media?parent=14248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/categories?post=14248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluetab.com\/es\/wp-json\/wp\/v2\/tags?post=14248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}